{"id":1744,"date":"2019-09-20T13:16:51","date_gmt":"2019-09-20T13:16:51","guid":{"rendered":"https:\/\/cloudsurfers.it\/dev?page_id=1744"},"modified":"2020-05-22T15:06:25","modified_gmt":"2020-05-22T15:06:25","slug":"i-nostri-prodotti","status":"publish","type":"page","link":"https:\/\/cloudsurfers.it\/index.php\/i-nostri-prodotti\/","title":{"rendered":"I nostri prodotti"},"content":{"rendered":"<h2 style=\"text-align: center;\"><strong>I NOSTRI PRODOTTI<\/strong><\/h2>\n<h3 style=\"text-align: center;\">Dai un occhiata alle nostre soluzioni software, trova quella per il tuo business<\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><div class=\"su-divider su-divider-style-double\" style=\"margin:30px 0;border-width:2px;border-color:#d3d2d2\"><\/div>\n<h2 style=\"text-align: left;\"><strong><a href=\"https:\/\/cloudsurfers.it?page_id=1846\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1842 size-full\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga_suite.png\" alt=\"\" width=\"297\" height=\"100\" \/><\/a>SAGA SUITE<\/strong><\/h2>\n<p>L&#8217;anello mancante tra ERP e CRM. Potrai consultare i dati della tua installazione locale del tuo ERP comodamente da web, potrai analizzare tutti i processi di business della tua azienda ed integrarli con le risorse del reparto marketing.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><div class=\"su-divider su-divider-style-double\" style=\"margin:30px 0;border-width:2px;border-color:#d3d2d2\"><\/div>\n<h2 style=\"text-align: right;\"><strong>PAYME<a href=\"https:\/\/cloudsurfers.it\/?page_id=1891\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1892 size-full\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/payme.png\" alt=\"\" width=\"145\" height=\"186\" \/><\/a><\/strong><\/h2>\n<p style=\"text-align: right;\">Vuoi un portale in cui esporre i tuoi prodotti e gestire la compravendita di licenze in modo rapido e personalizzabile? Payme \u00e8 la soluzione. Con Payme puoi gestire il tuo catalogo prodotti, personalizzare le licenze, modellare i preventivi per i tuoi clienti e gestire le transazioni con la sicurezza e la semplicit\u00e0 di Paypal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I NOSTRI PRODOTTI Dai un occhiata alle nostre soluzioni software, trova quella per il tuo business &nbsp; SAGA SUITE L&#8217;anello mancante tra ERP e CRM. Potrai consultare i dati della &#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"footnotes":""},"class_list":["post-1744","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages\/1744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/comments?post=1744"}],"version-history":[{"count":0,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages\/1744\/revisions"}],"wp:attachment":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/media?parent=1744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}