{"id":1846,"date":"2019-11-21T14:25:20","date_gmt":"2019-11-21T14:25:20","guid":{"rendered":"https:\/\/cloudsurfers.it\/dev?page_id=1846"},"modified":"2020-05-22T15:04:37","modified_gmt":"2020-05-22T15:04:37","slug":"saga","status":"publish","type":"page","link":"https:\/\/cloudsurfers.it\/index.php\/saga\/","title":{"rendered":"Saga"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1842 aligncenter\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga_suite.png\" alt=\"\" width=\"297\" height=\"100\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>Saga Suite<\/strong> \u00e8 un prodotto che sincronizza la base dati del tuo ERP\u00a0 installata nella tua azienda per fornirti tutti i dati del tuo ERP<\/p>\n<ul>\n<li>In velocit\u00e0<\/li>\n<li>Partizionando le informazioni in base all&#8217;utenza di accesso<\/li>\n<li>In mobilit\u00e0 tramite una pratica user interface ottimizzata per ambienti Desktop, Tablet e Smartphone<\/li>\n<\/ul>\n<p>Saga \u00e8 un portale che si rivolge a pi\u00f9 figure del processo aziendale, dando un taglio specifico delle informazioni visualizzabili a seconda del proprio ruolo.<\/p>\n<div class=\"container\">\n<div class=\"row mt-5\">\n<div class=\"col-md-6\">\n<h2>Amministra i tuoi dati<\/h2>\n<ul>\n<li>Gestire le utenze del software<\/li>\n<li>Visualizza tutti dati del tuo sistema<\/li>\n<li>Controlla il lavoro dei tuoi agenti<\/li>\n<li>Tieni sempre sotto controllo tutti i tuoi movimenti economici<\/li>\n<\/ul>\n<\/div>\n<div class=\"col-md-6\">\n<div style=\"width: 800px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1846-1\" width=\"800\" height=\"403\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-amministratore.mp4?_=1\" \/><a href=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-amministratore.mp4\">https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-amministratore.mp4<\/a><\/video><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"row mt-5\">\n<div class=\"col-md-6\">\n<div style=\"width: 800px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1846-2\" width=\"800\" height=\"403\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-cliente.mp4?_=2\" \/><a href=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-cliente.mp4\">https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-cliente.mp4<\/a><\/video><\/div>\n<\/div>\n<div class=\"col-md-6\">\n<h2>Per i clienti<\/h2>\n<ul>\n<li>Verifica che l&#8217;azienda abbia i tuoi dati aggiornati<\/li>\n<li>Consultare tutti i documenti di vendita (ordini &#8211; DDT &#8211; fatture)<\/li>\n<li>Visualizzare l&#8217;intero catalogo degli articoli<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"row mt-5\">\n<div class=\"col-md-6\">\n<h2>Per i fornitori<\/h2>\n<ul>\n<li>Verifica che l&#8217;azienda abbia i tuoi dati aggiornati<\/li>\n<li>Consultare tutti i documenti di acquisto (ordini &#8211; fatture &#8211; solleciti)<\/li>\n<li>Visualizzare l&#8217;intero catalogo degli articoli<\/li>\n<\/ul>\n<\/div>\n<div class=\"col-md-6\">\n<div style=\"width: 800px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1846-3\" width=\"800\" height=\"403\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-fornitore.mp4?_=3\" \/><a href=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-fornitore.mp4\">https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-fornitore.mp4<\/a><\/video><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"row mt-5\">\n<div class=\"col-md-6\">\n<div style=\"width: 800px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1846-4\" width=\"800\" height=\"403\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-agent.mp4?_=4\" \/><a href=\"https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-agent.mp4\">https:\/\/cloudsurfers.it\/wp-content\/uploads\/\/2019\/11\/saga-agent.mp4<\/a><\/video><\/div>\n<\/div>\n<div class=\"col-md-6\">\n<h2>Per gli agenti<\/h2>\n<ul>\n<li>Controlla l&#8217;elenco dei tuoi clienti<\/li>\n<li>Controlla lo scadenziario<\/li>\n<li>Organizza il calendario dei tuoi appuntamenti<\/li>\n<li>Prima di partire, dai un&#8217;occhiata a quale strada ti conviene percorrere<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:15px 0;border-width:2px;border-color:#999999\"><\/div>\n<h4 style=\"text-align: center;\">Desideri ulteriori informazioni?<\/h4>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/cloudsurfers.it\/?page_id=1794\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#2D89EF;border-color:#246ec0;border-radius:10px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#6cadf4;border-radius:10px;text-shadow:none\"> Contattaci<\/span><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Saga Suite \u00e8 un prodotto che sincronizza la base dati del tuo ERP\u00a0 installata nella tua azienda per fornirti tutti i dati del tuo ERP In velocit\u00e0 Partizionando le &#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"footnotes":""},"class_list":["post-1846","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":0,"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/pages\/1846\/revisions"}],"wp:attachment":[{"href":"https:\/\/cloudsurfers.it\/index.php\/wp-json\/wp\/v2\/media?parent=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}